{"id":41153,"date":"2026-02-11T12:08:34","date_gmt":"2026-02-11T11:08:34","guid":{"rendered":"https:\/\/evowatt.ch\/produit\/connettore-trasversale-insertionrail-2-0-su20-4\/"},"modified":"2026-02-11T16:28:25","modified_gmt":"2026-02-11T15:28:25","slug":"connettore-trasversale-insertionrail-2-0-su20-4","status":"publish","type":"product","link":"https:\/\/evowatt.ch\/it\/produit\/connettore-trasversale-insertionrail-2-0-su20-4\/","title":{"rendered":"CONNETTORE TRASVERSALE INSERTIONRAIL 2.0 (SU=20)"},"content":{"rendered":"<p>I componenti del sistema InsertionRail 2.0 non sono compatibili con il vecchio sistema InsertionRail. Il kit CrossConnector 2.0 semplifica il fissaggio dell&#8217;InsertionRail 2.0 a qualsiasi guida di montaggio K2. Le viti sono posizionate all&#8217;esterno del binario montato, consentendo di spostare il binario in verticale con il CrossConnector anche dopo l&#8217;installazione. Tutti gli accessori necessari per l&#8217;installazione sono inclusi nel kit. Materiale: alluminio EN-AW 6060 T66; acciaio inox 1.4301; A2-70    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>I componenti del sistema InsertionRail 2.0 non sono compatibili con il vecchio sistema InsertionRail. Il kit CrossConnector 2.0 semplifica il fissaggio dell&#8217;InsertionRail 2.0 a qualsiasi guida di montaggio K2. Le viti sono posizionate all&#8217;esterno del binario montato, consentendo di spostare il binario in verticale con il CrossConnector anche dopo l&#8217;installazione. Tutti gli accessori necessari per [&hellip;]<\/p>\n","protected":false},"featured_media":42332,"template":"","meta":{"_acf_changed":false},"product_brand":[616],"product_cat":[342],"product_tag":[],"class_list":["post-41153","product","type-product","status-publish","has-post-thumbnail","product_brand-k2-it-2","product_cat-sistemi-di-montaggio","first","onbackorder","taxable","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product\/41153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product\/41153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/media\/42332"}],"wp:attachment":[{"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/media?parent=41153"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product_brand?post=41153"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product_cat?post=41153"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/evowatt.ch\/it\/wp-json\/wp\/v2\/product_tag?post=41153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}